{"id":80,"date":"2018-03-20T17:22:51","date_gmt":"2018-03-20T17:22:51","guid":{"rendered":"https:\/\/demo.cocobasic.com\/kapena-wp\/?page_id=80"},"modified":"2025-08-04T10:33:15","modified_gmt":"2025-08-04T08:33:15","slug":"team","status":"publish","type":"page","link":"http:\/\/fundaciolluiscoromina.org\/index.php\/team\/","title":{"rendered":"Amics"},"content":{"rendered":"\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<\/div><div class=\"full-page-width center-relative\">\n<div class=\"team-holder \"><br \/>\n<div class=\"member one_third hover-effect\"><img decoding=\"async\" src=\"http:\/\/test.fundaciolluiscoromina.org\/wp-content\/uploads\/2025\/07\/unnamed.jpg\" alt=\"\"\/><div class=\"member-info\"><div class=\"member-name\">FRANCESC GUILLAMET<\/div><div class=\"member-social-holder\">\n<div class=\"social \"><a href=\"https:\/\/www.francescguillamet.com\/\" target=\"_blank\"><i class=\"fa fa-globe\"><\/i><\/a><\/div>\n<div class=\"social \"><a href=\"https:\/\/www.instagram.com\/guillametferran\/\" target=\"_blank\"><i class=\"fa fa-instagram\"><\/i><\/a><\/div>\n<\/div><\/div><\/div>\n<div class=\"member one_third \"><img decoding=\"async\" src=\"http:\/\/test.fundaciolluiscoromina.org\/wp-content\/uploads\/2025\/07\/9d30e5f6ee454dfca704a2657e1fa674.f5fb7444.jpg\" alt=\"\"\/><div class=\"member-info\"><div class=\"member-name\">JOSEP MI\u00c0S<\/div><div class=\"member-social-holder\">\n<div class=\"social \"><a href=\"https:\/\/miasarquitectes.com\/\" target=\"_blank\"><i class=\"fa fa-globe\"><\/i><\/a><\/div>\n<div class=\"social \"><a href=\"https:\/\/www.instagram.com\/miasarchitects\/\" target=\"_blank\"><i class=\"fa fa-instagram\"><\/i><\/a><\/div>\n<\/div><\/div><\/div>\n<div class=\"member one_third \"><img decoding=\"async\" src=\"http:\/\/test.fundaciolluiscoromina.org\/wp-content\/uploads\/2025\/07\/Tino-Soriano-1024x768-1.jpg\" alt=\"\"\/><div class=\"member-info\"><div class=\"member-name\">TINO SORIANO<\/div><div class=\"member-social-holder\">\n<div class=\"social \"><a href=\"https:\/\/www.tinosoriano.com\/es\/portada\" target=\"_blank\"><i class=\"fa fa-globe\"><\/i><\/a><\/div>\n<div class=\"social \"><a href=\"https:\/\/www.instagram.com\/tinosoriano\/\" target=\"_blank\"><i class=\"fa fa-instagram\"><\/i><\/a><\/div>\n<\/div><\/div><\/div>\n<div class=\"member one_third \"><img decoding=\"async\" src=\"http:\/\/test.fundaciolluiscoromina.org\/wp-content\/uploads\/2025\/07\/Yurian-Quintanas_Nobel.jpg\" alt=\"\"\/><div class=\"member-info\"><div class=\"member-name\">YURIAN QUINTANAS<\/div><div class=\"member-social-holder\">\n<div class=\"social \"><a href=\"https:\/\/yurianquintanas.com\" target=\"_blank\"><i class=\"fa fa-globe\"><\/i><\/a><\/div>\n<div class=\"social \"><a href=\"https:\/\/www.instagram.com\/yurian_quintanas\/\" target=\"_blank\"><i class=\"fa fa-instagram\"><\/i><\/a><\/div>\n<\/div><\/div><\/div>\n<div class=\"member one_third \"><img decoding=\"async\" src=\"http:\/\/test.fundaciolluiscoromina.org\/wp-content\/uploads\/2025\/07\/Captura-de-pantalla-2016-09-15-a-les-0.47.17.png\" alt=\"\"\/><div class=\"member-info\"><div class=\"member-name\">CARLES FONTSER\u00c8<\/div><div class=\"member-social-holder\">\n<div class=\"social \"><a href=\"http:\/\/www.carlesfontsere.cat\/\" target=\"_blank\"><i class=\"fa fa-globe\"><\/i><\/a><\/div>\n<div class=\"social \"><a href=\"https:\/\/www.facebook.com\/centenaricarlesfontsere\" target=\"_blank\"><i class=\"fa fa-facebook\"><\/i><\/a><\/div>\n<\/div><\/div><\/div>\n<div class=\"member one_third \"><img decoding=\"async\" src=\"http:\/\/test.fundaciolluiscoromina.org\/wp-content\/uploads\/2025\/07\/780_008_2971175_598af21b49e041aa4d9ef324b727f5fd.jpg\" alt=\"\"\/><div class=\"member-info\"><div class=\"member-name\">LLU\u00cdS VIL\u00c0<\/div><div class=\"member-social-holder\">\n<div class=\"social \"><a href=\"https:\/\/lluisvila.com\/\" target=\"_blank\"><i class=\"fa fa-globe\"><\/i><\/a><\/div>\n<\/div><\/div><\/div>\n<div class=\"clear\"><\/div><\/div><br \/>\n<\/div><div class=\"content-1170 center-relative\">\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-80","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/fundaciolluiscoromina.org\/index.php\/wp-json\/wp\/v2\/pages\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/fundaciolluiscoromina.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/fundaciolluiscoromina.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/fundaciolluiscoromina.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/fundaciolluiscoromina.org\/index.php\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":30,"href":"http:\/\/fundaciolluiscoromina.org\/index.php\/wp-json\/wp\/v2\/pages\/80\/revisions"}],"predecessor-version":[{"id":7141,"href":"http:\/\/fundaciolluiscoromina.org\/index.php\/wp-json\/wp\/v2\/pages\/80\/revisions\/7141"}],"wp:attachment":[{"href":"http:\/\/fundaciolluiscoromina.org\/index.php\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}